{"id":243,"date":"2019-12-04T21:35:47","date_gmt":"2019-12-04T20:35:47","guid":{"rendered":"http:\/\/bee-art.pl\/realizacje\/"},"modified":"2024-12-23T11:27:06","modified_gmt":"2024-12-23T10:27:06","slug":"realizacje-rodziny","status":"publish","type":"page","link":"https:\/\/bee-light.pl\/en\/realizacje-rodziny\/","title":{"rendered":"Completed Projects"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_empty_space]<div class=\"edgtf-portfolio-list-holder edgtf-pl-masonry edgtf-pl-normal-space edgtf-pl-five-columns edgtf-pl-gallery-slide-from-image-bottom edgtf-skin-light edgtf-pl-images-fixed edgtf-pl-has-shadow  edgtf-pl-pag-no-pagination edgtf-pl-has-filter    \"  data-type=masonry data-number-of-columns=5 data-space-between-items=normal data-number-of-items=-1 data-image-proportions=full data-enable-fixed-proportions=yes data-enable-image-shadow=yes data-order-by=date data-order=DESC data-item-style=gallery-slide-from-image-bottom data-overlay-skin=light data-enable-title=yes data-title-tag=h6 data-title-text-transform=uppercase data-enable-category=yes data-enable-count-images=yes data-enable-excerpt=yes data-excerpt-length=20 data-pagination-type=no-pagination data-filter=yes data-filter-order-by=name data-enable-article-animation=no data-portfolio-slider-on=no data-enable-loop=yes data-enable-autoplay=yes data-slider-speed=5000 data-slider-speed-animation=600 data-enable-navigation=yes data-enable-pagination=yes data-max-num-pages=0 data-next-page=2>\n\t\t<div class=\"edgtf-pl-filter-holder\" >\n\t\t<div class=\"edgtf-plf-inner\">\n\t\t\t\t\t\t\t<ul >\n\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\"\">\n\t\t\t\t\t\t<span>All<\/span>\n\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-aster-en\">\n\t\t\t\t\t\t\t<span >ASTER<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-calluna-en\">\n\t\t\t\t\t\t\t<span >CALLUNA<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-calluna-sq-en\">\n\t\t\t\t\t\t\t<span >CALLUNA SQ<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-clove-en\">\n\t\t\t\t\t\t\t<span >CLOVE<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-cortaderia-en\">\n\t\t\t\t\t\t\t<span >CORTADERIA<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-daisy-en\">\n\t\t\t\t\t\t\t<span >DAISY<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-daisy-hex-en\">\n\t\t\t\t\t\t\t<span >DAISY HEX<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-freesia-honeycomb-en\">\n\t\t\t\t\t\t\t<span >FREESIA HONEYCOMB<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-freesia-o-en\">\n\t\t\t\t\t\t\t<span >FREESIA O<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-freesia-sq-en\">\n\t\t\t\t\t\t\t<span >FREESIA SQ<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-honey-aro-en\">\n\t\t\t\t\t\t\t<span >HONEY ARO<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-honey-honeycomb\">\n\t\t\t\t\t\t\t<span >HONEY HONEYCOMB<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-honey-l-en\">\n\t\t\t\t\t\t\t<span >HONEY L<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-honey-ov-en\">\n\t\t\t\t\t\t\t<span >HONEY OV<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-honey-r-en\">\n\t\t\t\t\t\t\t<span >HONEY R<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-hoya-l-en\">\n\t\t\t\t\t\t\t<span >HOYA L<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-hoya-l-mini-en\">\n\t\t\t\t\t\t\t<span >HOYA L Mini<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-hoya-l-mini-2\">\n\t\t\t\t\t\t\t<span >HOYA L MINI<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-hoya-l-mini-30st-en\">\n\t\t\t\t\t\t\t<span >HOYA L MINI 30st<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-hoya-lz-en\">\n\t\t\t\t\t\t\t<span >HOYA LZ<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-hoya-t-en\">\n\t\t\t\t\t\t\t<span >HOYA T<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-iris-en\">\n\t\t\t\t\t\t\t<span >IRIS<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-ivy-m-g2-en\">\n\t\t\t\t\t\t\t<span >IVY M G2<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-ivy-os-en\">\n\t\t\t\t\t\t\t<span >IVY OS<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-lily-o-n-en\">\n\t\t\t\t\t\t\t<span >LILY O N<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-lily-o-p-en\">\n\t\t\t\t\t\t\t<span >LILY O P<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-lily-sq-n-en\">\n\t\t\t\t\t\t\t<span >LILY SQ N<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-lily-sq-p-en\">\n\t\t\t\t\t\t\t<span >LILY SQ P<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-mallow-en\">\n\t\t\t\t\t\t\t<span >MALLOW<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-mallow-mini-en\">\n\t\t\t\t\t\t\t<span >MALLOW MINI<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-nemesia-in-en\">\n\t\t\t\t\t\t\t<span >NEMESIA IN<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-nemesia-k-en\">\n\t\t\t\t\t\t\t<span >NEMESIA K<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-nemesia-n-en\">\n\t\t\t\t\t\t\t<span >NEMESIA N<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-nemesia-od-k-en\">\n\t\t\t\t\t\t\t<span >NEMESIA OD K<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-orchid-3d-en\">\n\t\t\t\t\t\t\t<span >ORCHID 3D<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-orchid-3f-en\">\n\t\t\t\t\t\t\t<span >ORCHID 3F<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-orchid-gk-en\">\n\t\t\t\t\t\t\t<span >ORCHID GK<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-orchid-gk-2\">\n\t\t\t\t\t\t\t<span >ORCHID GK<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-orchid-k-en\">\n\t\t\t\t\t\t\t<span >ORCHID K<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-orchid-l-en\">\n\t\t\t\t\t\t\t<span >ORCHID L<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-orchid-linia-en\">\n\t\t\t\t\t\t\t<span >ORCHID LINIA<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-orchid-n-en\">\n\t\t\t\t\t\t\t<span >ORCHID N<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-orchid-od-n-en\">\n\t\t\t\t\t\t\t<span >ORCHID OD N<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-orchid-p-en\">\n\t\t\t\t\t\t\t<span >ORCHID P<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-orchid-pz-en\">\n\t\t\t\t\t\t\t<span >ORCHID PZ<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-orchid-sq-en\">\n\t\t\t\t\t\t\t<span >ORCHID SQ<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-orchid-tr-en\">\n\t\t\t\t\t\t\t<span >ORCHID TR<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-orchid-v-en\">\n\t\t\t\t\t\t\t<span >ORCHID V<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-pansy-en\">\n\t\t\t\t\t\t\t<span >PANSY<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-peony-en\">\n\t\t\t\t\t\t\t<span >PEONY<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-poppy-en\">\n\t\t\t\t\t\t\t<span >POPPY O<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-poppy-sq-en\">\n\t\t\t\t\t\t\t<span >POPPY SQ<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-primrose-en\">\n\t\t\t\t\t\t\t<span >PRIMROSE<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-rose-2\">\n\t\t\t\t\t\t\t<span >ROSE<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-rugosa-k-en\">\n\t\t\t\t\t\t\t<span >RUGOSA K<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-snapdragon-en\">\n\t\t\t\t\t\t\t<span >SNAPDRAGON<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-tagetes-en\">\n\t\t\t\t\t\t\t<span >TAGETES<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"edgtf-pl-filter\" data-filter=\".portfolio-category-tulip-en\">\n\t\t\t\t\t\t\t<span >TULIP<\/span>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t\n\t<div class=\"edgtf-pl-inner clearfix\">\n\t\t<div class=\"edgtf-pl-grid-sizer\"><\/div>\n\t\t<div class=\"edgtf-pl-grid-gutter\"><\/div>\n\t\t\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-15467 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-snapdragon-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01179-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01179-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01179-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tSNAPDRAGON\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/snapdragon-en\/\">SNAPDRAGON<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Szko\u0142a Podstawowa 4<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/snapdragon-2\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-15452 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-ivy-m-g2-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01248-2-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01248-2-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01248-2-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tIVY M G2\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/ivy-m-g2-en\/\">IVY M G2<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Szko\u0142a Podstawowa 4<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/ivy-m-g2\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-15423 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-daisy-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01224-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01224-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01224-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tDAISY\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/daisy-en\/\">DAISY<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Szko\u0142a Podstawowa 4<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/daisy-9\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-15370 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-tulip-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01246-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01246-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01246-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tTULIP L\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/tulip-en\/\">TULIP<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Osiedle Marynin w Wa<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/tulip-l\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-15358 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-n-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01261-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01261-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01261-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID N\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-n-en\/\">ORCHID N<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Osiedle Marynin w Wa<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-n-13\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-15343 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-mallow-mini-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01250-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01250-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01250-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tMALLOW MINI\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/mallow-mini-en\/\">MALLOW MINI<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Osiedle Marynin w Wa<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/mallow-mini-2\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-15334 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-hoya-l-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01279-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01279-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01279-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHOYA L\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/hoya-l-en\/\">HOYA L<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Osiedle Marynin w Wa<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/hoya-l-10\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-15313 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-aster-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01268-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01268-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01268-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tASTER\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/aster-en\/\">ASTER<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Osiedle Marynin w Wa<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/aster-16\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-15308 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-hoya-l-mini-30st-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01308-2-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01308-2-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01308-2-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHOYA L MINI 30st\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/hoya-l-mini-30st-en\/\">HOYA L MINI 30st<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Osiedle Goslove w Wa<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/hoya-l-mini-30st-2\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-15295 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-hoya-l-mini portfolio-category-hoya-l-mini-2\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01292-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01292-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01292-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHOYA L MINI\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/portfolio-category\/hoya-l-mini\/\">HOYA L Mini<\/a>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/hoya-l-mini-2\/\">HOYA L MINI<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Osiedle Goslove w Wa<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/hoya-l-mini-8\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-15288 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-honey-r-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01317-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01317-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01317-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHONEY R\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/honey-r-en\/\">HONEY R<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Osiedle Goslove w Wa<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/honey-r-9\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-15278 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-daisy-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01320-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01320-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01320-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tDAISY N\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/daisy-en\/\">DAISY<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Osiedle Goslove w Wa<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/daisy-n\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-15263 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-cortaderia-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01291-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01291-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01291-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tCORTADERIA\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/cortaderia-en\/\">CORTADERIA<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Osiedle Goslove w Wa<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/cortaderia-6\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-15246 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-clove-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01308-1-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01308-1-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01308-1-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tCLOVE 45\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/clove-en\/\">CLOVE<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Osiedle Goslove w Wa<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/clove-45\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-15239 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-snapdragon-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01327-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01327-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01327-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tSNAPDRAGON\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/snapdragon-en\/\">SNAPDRAGON<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Publiczna Szko\u0142a Po<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/snapdragon\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-15216 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-hoya-t-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01300-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01300-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01300-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHOYA T\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/hoya-t-en\/\">HOYA T<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Publiczna Szko\u0142a Po<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/hoya-t-5\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-15206 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-hoya-l-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01372-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01372-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01372-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHOYA L\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/hoya-l-en\/\">HOYA L<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Publiczna Szko\u0142a Po<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/hoya-l-9\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-15199 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-honey-honeycomb\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01306-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01306-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01306-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHONEY HONEYCOMB\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/honey-honeycomb\/\">HONEY HONEYCOMB<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Publiczna Szko\u0142a Po<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/15177\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-15176 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-freesia-honeycomb-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01358-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01358-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01358-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tFREESIA HONEYCOMB\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/freesia-honeycomb-en\/\">FREESIA HONEYCOMB<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Publiczna Szko\u0142a Po<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/freesia-honeycomb-3\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-15161 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-freesia-honeycomb-en portfolio-category-rugosa-k-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01338-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01338-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01338-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tRUGOSA K | FREESIA HONEYCOMB\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/freesia-honeycomb-en\/\">FREESIA HONEYCOMB<\/a>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/rugosa-k-en\/\">RUGOSA K<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Publiczna Szko\u0142a Po<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/rugosa-k-freesia-honeycomb\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-15156 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-poppy-sq-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01346-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01346-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01346-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tPOPPY SQ\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/poppy-sq-en\/\">POPPY SQ<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Publiczna Szko\u0142a Po<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/poppy-sq\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-15150 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-freesia-honeycomb-en portfolio-category-orchid-n-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01344-1-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01344-1-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2026\/03\/DSC01344-1-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID N | FREESIA HONEYCOMB\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/freesia-honeycomb-en\/\">FREESIA HONEYCOMB<\/a>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-n-en\/\">ORCHID N<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Publiczna Szko\u0142a Po<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-n-freesia-honeycomb\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-15136 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-peony-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2025\/10\/DSC00980-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2025\/10\/DSC00980-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2025\/10\/DSC00980-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2025\/10\/DSC00980-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2025\/10\/DSC00980-100x100.jpg 100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tPEONY\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/peony-en\/\">PEONY<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/peony-2\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-14597 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-l-en portfolio-category-orchid-linia-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2025\/05\/IMG_6932-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2025\/05\/IMG_6932-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2025\/05\/IMG_6932-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2025\/05\/IMG_6932-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2025\/05\/IMG_6932-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2025\/05\/IMG_6932-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID L\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-l-en\/\">ORCHID L<\/a>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-linia-en\/\">ORCHID LINIA<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-l\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13682 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-daisy-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2025\/01\/IMG-20250131-WA0008-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2025\/01\/IMG-20250131-WA0008-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2025\/01\/IMG-20250131-WA0008-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2025\/01\/IMG-20250131-WA0008-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2025\/01\/IMG-20250131-WA0008-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2025\/01\/IMG-20250131-WA0008-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tDAISY\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/daisy-en\/\">DAISY<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/daisy-8\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13686 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-3f-en portfolio-category-tulip\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2025\/01\/IMG-20250131-WA0003-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2025\/01\/IMG-20250131-WA0003-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2025\/01\/IMG-20250131-WA0003-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2025\/01\/IMG-20250131-WA0003-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2025\/01\/IMG-20250131-WA0003-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2025\/01\/IMG-20250131-WA0003-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID 3F\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-3f-en\/\">ORCHID 3F<\/a>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/portfolio-category\/tulip\/\">TULIP<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-3f\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13688 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-tulip-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2025\/01\/IMG-20250131-WA0002-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2025\/01\/IMG-20250131-WA0002-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2025\/01\/IMG-20250131-WA0002-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2025\/01\/IMG-20250131-WA0002-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2025\/01\/IMG-20250131-WA0002-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2025\/01\/IMG-20250131-WA0002-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tTulip\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/tulip-en\/\">TULIP<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/tulip-3\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13690 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-calluna-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2025\/01\/IMG-20250122-WA0003-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2025\/01\/IMG-20250122-WA0003-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2025\/01\/IMG-20250122-WA0003-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2025\/01\/IMG-20250122-WA0003-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2025\/01\/IMG-20250122-WA0003-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2025\/01\/IMG-20250122-WA0003-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tCALLUNA\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/calluna-en\/\">CALLUNA<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/calluna\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13692 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-pansy-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2025\/01\/IMG-20250122-WA0001-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2025\/01\/IMG-20250122-WA0001-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2025\/01\/IMG-20250122-WA0001-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2025\/01\/IMG-20250122-WA0001-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2025\/01\/IMG-20250122-WA0001-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2025\/01\/IMG-20250122-WA0001-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tPANSY\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/pansy-en\/\">PANSY<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/pansy-6\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13694 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-clove-en portfolio-category-tulip-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"480\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/12\/Bee-Light-Image-2024-12-05-at-15.39.01.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/12\/Bee-Light-Image-2024-12-05-at-15.39.01.jpeg 360w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/12\/Bee-Light-Image-2024-12-05-at-15.39.01-225x300.jpeg 225w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tTULIP CLOVE\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/clove-en\/\">CLOVE<\/a>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/tulip-en\/\">TULIP<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/tulip-clove\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13696 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-3d-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/12\/Bee-Light-Image-2024-12-16-at-13.44.16-1-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/12\/Bee-Light-Image-2024-12-16-at-13.44.16-1-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/12\/Bee-Light-Image-2024-12-16-at-13.44.16-1-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/12\/Bee-Light-Image-2024-12-16-at-13.44.16-1-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/12\/Bee-Light-Image-2024-12-16-at-13.44.16-1-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/12\/Bee-Light-Image-2024-12-16-at-13.44.16-1-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID 3D\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-3d-en\/\">ORCHID 3D<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-3d\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13698 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-v-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/12\/Bee-Light-Image-2024-12-06-at-14.48.16-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/12\/Bee-Light-Image-2024-12-06-at-14.48.16-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/12\/Bee-Light-Image-2024-12-06-at-14.48.16-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/12\/Bee-Light-Image-2024-12-06-at-14.48.16-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/12\/Bee-Light-Image-2024-12-06-at-14.48.16-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/12\/Bee-Light-Image-2024-12-06-at-14.48.16-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID V\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-v-en\/\">ORCHID V<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-v\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13700 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-honey-r-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/beelight-Image-2024-10-28-at-12.38.17-2-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/beelight-Image-2024-10-28-at-12.38.17-2-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/beelight-Image-2024-10-28-at-12.38.17-2-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/beelight-Image-2024-10-28-at-12.38.17-2-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/beelight-Image-2024-10-28-at-12.38.17-2-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/beelight-Image-2024-10-28-at-12.38.17-2-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHONEY R\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/honey-r-en\/\">HONEY R<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/honey-r-8\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13702 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-pz-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/beelight-Image-2024-10-28-at-12.38.21-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/beelight-Image-2024-10-28-at-12.38.21-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/beelight-Image-2024-10-28-at-12.38.21-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/beelight-Image-2024-10-28-at-12.38.21-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/beelight-Image-2024-10-28-at-12.38.21-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/beelight-Image-2024-10-28-at-12.38.21-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID PZ\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-pz-en\/\">ORCHID PZ<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-pz-7\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13704 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-honey-aro-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/beelight-Image-2024-10-28-at-12.38.17-1-1-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/beelight-Image-2024-10-28-at-12.38.17-1-1-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/beelight-Image-2024-10-28-at-12.38.17-1-1-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/beelight-Image-2024-10-28-at-12.38.17-1-1-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/beelight-Image-2024-10-28-at-12.38.17-1-1-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/beelight-Image-2024-10-28-at-12.38.17-1-1-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHONEY ARO\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/honey-aro-en\/\">HONEY ARO<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/honey-aro\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13706 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-daisy-hex-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/beelight-Image-2024-10-28-at-12.38.15-2-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/beelight-Image-2024-10-28-at-12.38.15-2-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/beelight-Image-2024-10-28-at-12.38.15-2-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/beelight-Image-2024-10-28-at-12.38.15-2-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/beelight-Image-2024-10-28-at-12.38.15-2-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/beelight-Image-2024-10-28-at-12.38.15-2-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tDAISY HEX\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/daisy-hex-en\/\">DAISY HEX<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/daisy-hex\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13708 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-freesia-o-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/beelight-Image-2024-10-28-at-12.38.15-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/beelight-Image-2024-10-28-at-12.38.15-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/beelight-Image-2024-10-28-at-12.38.15-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/beelight-Image-2024-10-28-at-12.38.15-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/beelight-Image-2024-10-28-at-12.38.15-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/beelight-Image-2024-10-28-at-12.38.15-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tFREESIA O\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/freesia-o-en\/\">FREESIA O<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/freesia-o-5\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13710 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-honey-honeycomb\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/PHOTO-2024-02-14-12-25-18-1-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/PHOTO-2024-02-14-12-25-18-1-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/PHOTO-2024-02-14-12-25-18-1-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/PHOTO-2024-02-14-12-25-18-1-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/PHOTO-2024-02-14-12-25-18-1-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/PHOTO-2024-02-14-12-25-18-1-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHoney Honeycomb\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/honey-honeycomb\/\">HONEY HONEYCOMB<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/honey-honeycomb-3\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13712 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-honey-ov-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/OV_honey-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/OV_honey-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/OV_honey-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/OV_honey-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/OV_honey-150x150.jpeg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHoney OV\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/honey-ov-en\/\">HONEY OV<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/honey-ov\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13714 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-hoya-l-mini-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/beelight-Image-2024-10-04-at-19.22.42-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/beelight-Image-2024-10-04-at-19.22.42-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/beelight-Image-2024-10-04-at-19.22.42-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/beelight-Image-2024-10-04-at-19.22.42-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/beelight-Image-2024-10-04-at-19.22.42-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/beelight-Image-2024-10-04-at-19.22.42-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHoya L Mini\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/hoya-l-mini-en\/\">HOYA L Mini<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/hoya-l-mini-7\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13716 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-hoya-l-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/beelight-Image-2024-10-04-at-19.22.41-1-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/beelight-Image-2024-10-04-at-19.22.41-1-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/beelight-Image-2024-10-04-at-19.22.41-1-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/beelight-Image-2024-10-04-at-19.22.41-1-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/beelight-Image-2024-10-04-at-19.22.41-1-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/10\/beelight-Image-2024-10-04-at-19.22.41-1-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHOYA L\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/hoya-l-en\/\">HOYA L<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/hoya-l-8\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13718 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-primrose-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09794-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09794-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09794-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09794-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09794-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tPRIMROSE\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/primrose-en\/\">PRIMROSE<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Primo III \u0141\u00f3d\u017a<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/primrose-3\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13720 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-aster-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09829-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09829-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09829-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09829-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09829-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tASTER\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/aster-en\/\">ASTER<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Primo III \u0141\u00f3d\u017a<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/aster-15\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13722 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-honey-r-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09811-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09811-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09811-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09811-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09811-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHONEY R\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/honey-r-en\/\">HONEY R<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Primo III \u0141\u00f3d\u017a<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/honey-r-7\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13724 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-n-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09822-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09822-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09822-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09822-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09822-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-n-en\/\">ORCHID N<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Primo III \u0141\u00f3d\u017a<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-2\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13726 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-hoya-l-mini-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09839-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09839-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09839-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09839-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09839-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHOYA L MINI\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/hoya-l-mini-en\/\">HOYA L Mini<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Primo III \u0141\u00f3d\u017a<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/hoya-l-mini-6\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13728 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-clove-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09865-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09865-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09865-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09865-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09865-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tCLOVE\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/clove-en\/\">CLOVE<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">DAF Truck Service<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/clove-5\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13730 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-pz-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09864-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09864-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09864-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09864-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09864-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID PZ\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-pz-en\/\">ORCHID PZ<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">DAF Truck Service<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-pz-6\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13733 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-daisy-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09861-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09861-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09861-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09861-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09861-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tDAISY\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/daisy-en\/\">DAISY<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">DAF Truck Service<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/daisy-7\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13735 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-aster-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09853-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09853-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09853-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09853-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09853-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tASTER\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/aster-en\/\">ASTER<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">DAF Truck Service<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/aster-14\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13737 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-hoya-l-mini-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09880-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09880-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09880-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09880-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09880-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHOYA L MINI\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/hoya-l-mini-en\/\">HOYA L Mini<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">na Bielany<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/hoya-l-mini-5\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13739 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-tag-feverfew\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09920-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09920-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09920-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09920-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09920-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tFEVERFEW\t<\/h6>\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">na Bielany<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/feverfew\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13741 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-p-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09908-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09908-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09908-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09908-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09908-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID P\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-p-en\/\">ORCHID P<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">na Bielany<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-p-7\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13743 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-p-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09880-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09880-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09880-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09880-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09880-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID P\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-p-en\/\">ORCHID P<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">na Bielany<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-p-6\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13745 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-sq-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09884-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09884-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09884-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09884-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09884-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID SQ\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-sq-en\/\">ORCHID SQ<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">na Bielany<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-sq-4\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13747 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-aster-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09909-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09909-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09909-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09909-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09909-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tASTER\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/aster-en\/\">ASTER<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">na Bielany<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/aster-13\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13749 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-k-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09943-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09943-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09943-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09943-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09943-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID K2\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-k-en\/\">ORCHID K<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Szpital Czerniakowsk<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-k2-2\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13751 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-tag-rugosa\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09956-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09956-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09956-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09956-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09956-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tRUGOSA\t<\/h6>\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Szpital Czerniakowsk<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-k2\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13753 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-lily-o-p-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09955-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09955-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09955-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09955-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09955-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tLILY O P\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/lily-o-p-en\/\">LILY O P<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Szpital Czerniakowsk<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/lily-o-p-5\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13755 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-sq-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09951-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09951-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09951-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09951-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09951-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID SQ P\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-sq-en\/\">ORCHID SQ<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Szpital Czerniakowsk<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-sq-p\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13757 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-aster-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09958-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09958-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09958-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09958-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09958-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tASTER\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/aster-en\/\">ASTER<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Szpital Czerniakowsk<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/aster-12\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13759 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-p-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09954-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09954-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09954-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09954-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09954-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID P\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-p-en\/\">ORCHID P<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Szpital Czerniakowsk<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-p-5\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13761 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-daisy-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09926-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09926-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09926-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09926-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09926-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tDAISY\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/daisy-en\/\">DAISY<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Szpital Czerniakowsk<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/daisy-6\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13763 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-sq-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09971-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09971-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09971-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09971-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09971-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID SQ\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-sq-en\/\">ORCHID SQ<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Urz\u0105d Gminy Bielany<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-sq-3\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13765 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-freesia-o-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09977-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09977-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09977-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09977-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09977-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tFREESIA O\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/freesia-o-en\/\">FREESIA O<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Urz\u0105d Gminy Bielany<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/freesia-o-4\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13767 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-clove-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09984-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09984-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09984-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09984-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09984-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tCLOVE\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/clove-en\/\">CLOVE<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Urz\u0105d Gminy Bielany<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/clove-4\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13769 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-lily-sq-p-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09994-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09994-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09994-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09994-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09994-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tLILY SQ P\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/lily-sq-p-en\/\">LILY SQ P<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Urz\u0105d Gminy Bielany<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/clove-3\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13771 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-pz-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09987-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09987-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09987-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09987-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC09987-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID PZ\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-pz-en\/\">ORCHID PZ<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Urz\u0105d Gminy Bielany<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-pz-5\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13773 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-daisy-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC10010-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC10010-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC10010-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC10010-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/08\/DSC10010-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tDAISY\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/daisy-en\/\">DAISY<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Urz\u0105d Gminy Bielany<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/daisy-5\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13777 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-aster-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/07\/20201113_120713000_iOS-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/07\/20201113_120713000_iOS-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/07\/20201113_120713000_iOS-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/07\/20201113_120713000_iOS-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/07\/20201113_120713000_iOS-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/07\/20201113_120713000_iOS-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tASTER\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/aster-en\/\">ASTER<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/aster-11\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13779 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-aster-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/07\/20200914_131855-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/07\/20200914_131855-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/07\/20200914_131855-scaled-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/07\/20200914_131855-scaled-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/07\/20200914_131855-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/07\/20200914_131855-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tASTER\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/aster-en\/\">ASTER<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/aster-10\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13781 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-aster-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/07\/20200914_112710-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/07\/20200914_112710-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/07\/20200914_112710-scaled-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/07\/20200914_112710-scaled-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/07\/20200914_112710-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/07\/20200914_112710-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tASTER\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/aster-en\/\">ASTER<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/aster-9\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13783 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-aster-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/07\/20200914_112306-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/07\/20200914_112306-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/07\/20200914_112306-scaled-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/07\/20200914_112306-scaled-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/07\/20200914_112306-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/07\/20200914_112306-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tASTER\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/aster-en\/\">ASTER<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/aster-8\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13785 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-hoya-l-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2021-03-10-at-13.43.22-2-1-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2021-03-10-at-13.43.22-2-1-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2021-03-10-at-13.43.22-2-1-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2021-03-10-at-13.43.22-2-1-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2021-03-10-at-13.43.22-2-1-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2021-03-10-at-13.43.22-2-1-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHOYA L\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/hoya-l-en\/\">HOYA L<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/hoya-l-7\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13787 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-hoya-l-mini-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2021-03-10-at-13.43.23-1-2-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2021-03-10-at-13.43.23-1-2-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2021-03-10-at-13.43.23-1-2-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2021-03-10-at-13.43.23-1-2-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2021-03-10-at-13.43.23-1-2-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2021-03-10-at-13.43.23-1-2-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHOYA L MINI\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/hoya-l-mini-en\/\">HOYA L Mini<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/hoya-l-mini-4\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13789 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-hoya-t-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2021-03-10-at-13.42.00-2-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2021-03-10-at-13.42.00-2-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2021-03-10-at-13.42.00-2-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2021-03-10-at-13.42.00-2-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2021-03-10-at-13.42.00-2-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2021-03-10-at-13.42.00-2-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHOYA T\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/hoya-t-en\/\">HOYA T<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/hoya-t-4\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13791 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-nemesia-in-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/perlowa4-2-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/perlowa4-2-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/perlowa4-2-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/perlowa4-2-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/perlowa4-2-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/perlowa4-2-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tNEMESIA IN\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/nemesia-in-en\/\">NEMESIA IN<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/nemesia-in-4\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13793 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-gk-en portfolio-category-orchid-pz-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/przestrzen-biurowa-orchid-pz4-1-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/przestrzen-biurowa-orchid-pz4-1-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/przestrzen-biurowa-orchid-pz4-1-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/przestrzen-biurowa-orchid-pz4-1-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/przestrzen-biurowa-orchid-pz4-1-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-gk-en\/\">ORCHID GK<\/a>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-pz-en\/\">ORCHID PZ<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13795 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-aster-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09711-1-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09711-1-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09711-1-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09711-1-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09711-1-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tASTER\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/aster-en\/\">ASTER<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/aster-7\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13797 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-n-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09698-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09698-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09698-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09698-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09698-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID N\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-n-en\/\">ORCHID N<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-n-12\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13799 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-hoya-l\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG_5022-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG_5022-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG_5022-scaled-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG_5022-scaled-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG_5022-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG_5022-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHOYA L MINI\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/portfolio-category\/hoya-l\/\">HOYA L<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/hoya-l-mini-3\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13801 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-nemesia-od-k-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG_1048-1-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG_1048-1-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG_1048-1-scaled-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG_1048-1-scaled-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG_1048-1-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG_1048-1-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tNEMESIA OD K\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/nemesia-od-k-en\/\">NEMESIA OD K<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/nemesia-od-k-2\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13803 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-p-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/904-1-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/904-1-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/904-1-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/904-1-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/904-1-150x150.jpeg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID P\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-p-en\/\">ORCHID P<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-p-4\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13805 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-honey-r-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/557-2-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/557-2-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/557-2-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/557-2-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/557-2-150x150.jpeg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHONEY R\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/honey-r-en\/\">HONEY R<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/honey-r-6\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13807 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-lily-o-p-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09624-1-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09624-1-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09624-1-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09624-1-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09624-1-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tLILY O P\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/lily-o-p-en\/\">LILY O P<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/lily-o-p-4\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13809 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-k-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09630-3-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09630-3-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09630-3-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09630-3-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09630-3-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHOD K\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-k-en\/\">ORCHID K<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchod-k\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13811 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-n-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09615-1-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09615-1-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09615-1-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09615-1-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09615-1-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID N\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-n-en\/\">ORCHID N<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-n-11\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13813 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-daisy-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/11-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/11-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/11-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/11-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/11-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tDAISY\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/daisy-en\/\">DAISY<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/daisy-4\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13815 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-od-n-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/03-2-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/03-2-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/03-2-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/03-2-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/03-2-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID OD N\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-od-n-en\/\">ORCHID OD N<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-od-n-3\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13817 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-cortaderia-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG-20220721-WA0004-2-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG-20220721-WA0004-2-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG-20220721-WA0004-2-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG-20220721-WA0004-2-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG-20220721-WA0004-2-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG-20220721-WA0004-2-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tCORTADERIA\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/cortaderia-en\/\">CORTADERIA<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/cortaderia-5\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13819 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-pansy-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG-20220721-WA0006-2-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG-20220721-WA0006-2-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG-20220721-WA0006-2-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG-20220721-WA0006-2-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG-20220721-WA0006-2-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG-20220721-WA0006-2-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tPANSY\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/pansy-en\/\">PANSY<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/pansy-5\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13821 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-hoya-l-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG-20220721-WA0003-2-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG-20220721-WA0003-2-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG-20220721-WA0003-2-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG-20220721-WA0003-2-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG-20220721-WA0003-2-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG-20220721-WA0003-2-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHOYA L\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/hoya-l-en\/\">HOYA L<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/hoya-l-6\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13823 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-hoya-t-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG-20220721-WA0002-1-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG-20220721-WA0002-1-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG-20220721-WA0002-1-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG-20220721-WA0002-1-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG-20220721-WA0002-1-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG-20220721-WA0002-1-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHOYA T\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/hoya-t-en\/\">HOYA T<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/hoya-t-3\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13825 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-nemesia-od-k-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09782-1-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09782-1-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09782-1-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09782-1-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09782-1-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tNEMESIA K\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/nemesia-od-k-en\/\">NEMESIA OD K<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/nemesia-k\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13827 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-pz-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG_4970-1-2-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG_4970-1-2-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG_4970-1-2-scaled-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG_4970-1-2-scaled-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG_4970-1-2-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG_4970-1-2-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID PZ\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-pz-en\/\">ORCHID PZ<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-pz-4\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13829 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-linia-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG_4972-1-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG_4972-1-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG_4972-1-scaled-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG_4972-1-scaled-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG_4972-1-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/IMG_4972-1-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID LINIA\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-linia-en\/\">ORCHID LINIA<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-linia\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13831 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-aster-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/Bee-Light-Image-2021-12-14-at-10.46.11-1-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/Bee-Light-Image-2021-12-14-at-10.46.11-1-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/Bee-Light-Image-2021-12-14-at-10.46.11-1-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/Bee-Light-Image-2021-12-14-at-10.46.11-1-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/Bee-Light-Image-2021-12-14-at-10.46.11-1-150x150.jpeg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tASTER\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/aster-en\/\">ASTER<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/aster-6\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13833 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-aster-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09672-1-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09672-1-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09672-1-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09672-1-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09672-1-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tASTER\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/aster-en\/\">ASTER<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/aster-5\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13835 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-lily-o-n-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09653-1-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09653-1-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09653-1-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09653-1-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09653-1-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tLILY O N\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/lily-o-n-en\/\">LILY O N<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/lily-o-n-2\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13837 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-calluna-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09637-1-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09637-1-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09637-1-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09637-1-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09637-1-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tCALLUNA O\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/calluna-en\/\">CALLUNA<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/calluna-o-2\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13839 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-hoya-t-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/05\/beelight-Image-2024-05-07-at-21.14.22-3-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/05\/beelight-Image-2024-05-07-at-21.14.22-3-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/05\/beelight-Image-2024-05-07-at-21.14.22-3-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/05\/beelight-Image-2024-05-07-at-21.14.22-3-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/05\/beelight-Image-2024-05-07-at-21.14.22-3-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/05\/beelight-Image-2024-05-07-at-21.14.22-3-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHOYA T\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/hoya-t-en\/\">HOYA T<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/hoya-t-2\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13841 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-calluna-sq-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09779-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09779-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09779-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09779-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09779-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tCALLUNA SQ\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/calluna-sq-en\/\">CALLUNA SQ<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/calluna-sq-3\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13843 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-n-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09786-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09786-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09786-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09786-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09786-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID N\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-n-en\/\">ORCHID N<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-n-10\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13845 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-k-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09758-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09758-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09758-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09758-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09758-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID K DYS\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-k-en\/\">ORCHID K<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-k-dys\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13847 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-nemesia-n-en portfolio-category-nemesia-od-k-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09780-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09780-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09780-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09780-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09780-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tNEMESIA N NEMESIA K\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/nemesia-n-en\/\">NEMESIA N<\/a>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/nemesia-od-k-en\/\">NEMESIA OD K<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/nemesia-n-nemesia-k\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13849 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-tr-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09749-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09749-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09749-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09749-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09749-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID TR\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-tr-en\/\">ORCHID TR<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-tr\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13851 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-nemesia-in-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09739-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09739-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09739-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09739-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/06\/DSC09739-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tNEMESIA IN OD 205\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/nemesia-in-en\/\">NEMESIA IN<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/nemesia-in-od-205\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13853 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-honey-r-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/05\/IMG_1647-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/05\/IMG_1647-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/05\/IMG_1647-scaled-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/05\/IMG_1647-scaled-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/05\/IMG_1647-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/05\/IMG_1647-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHONEY R\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/honey-r-en\/\">HONEY R<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">HONEY R<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/honey-r-5\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13855 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-honey-l-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/05\/IMG_1622-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/05\/IMG_1622-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/05\/IMG_1622-scaled-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/05\/IMG_1622-scaled-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/05\/IMG_1622-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/05\/IMG_1622-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHONEY L\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/honey-l-en\/\">HONEY L<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/honey-l\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13857 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-cortaderia-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/05\/DJI_20240429203444_0406_D-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/05\/DJI_20240429203444_0406_D-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/05\/DJI_20240429203444_0406_D-scaled-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/05\/DJI_20240429203444_0406_D-scaled-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/05\/DJI_20240429203444_0406_D-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/05\/DJI_20240429203444_0406_D-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tCORTADERIA\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/cortaderia-en\/\">CORTADERIA<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">CORTADERIA<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/cortaderia-4\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13859 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-hoya-lz-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/05\/beelight-Image-2024-05-07-at-21.14.23-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/05\/beelight-Image-2024-05-07-at-21.14.23-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/05\/beelight-Image-2024-05-07-at-21.14.23-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/05\/beelight-Image-2024-05-07-at-21.14.23-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/05\/beelight-Image-2024-05-07-at-21.14.23-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/05\/beelight-Image-2024-05-07-at-21.14.23-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHOYA LZ\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/hoya-lz-en\/\">HOYA LZ<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/hoya-lz-2\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-11508 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-nemesia-od-k-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/05\/BEELIGHT-Image-2024-05-14-at-09.53.41-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/05\/BEELIGHT-Image-2024-05-14-at-09.53.41-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/05\/BEELIGHT-Image-2024-05-14-at-09.53.41-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/05\/BEELIGHT-Image-2024-05-14-at-09.53.41-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/05\/BEELIGHT-Image-2024-05-14-at-09.53.41-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/05\/BEELIGHT-Image-2024-05-14-at-09.53.41-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tNEMESIA OD K\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/nemesia-od-k-en\/\">NEMESIA OD K<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/nemesia-od-k\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10935 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-cortaderia-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/04\/IMG_1058-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/04\/IMG_1058-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/04\/IMG_1058-scaled-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/04\/IMG_1058-scaled-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/04\/IMG_1058-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/04\/IMG_1058-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tCORTADERIA\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/cortaderia-en\/\">CORTADERIA<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Dream Park<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/cortaderia-3\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10937 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-cortaderia-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/IMG_4850-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/IMG_4850-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/IMG_4850-scaled-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/IMG_4850-scaled-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/IMG_4850-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/IMG_4850-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tCORTADERIA\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/cortaderia-en\/\">CORTADERIA<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/cortaderia-2\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10939 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-cortaderia-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/IMG_6634-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/IMG_6634-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/IMG_6634-scaled-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/IMG_6634-scaled-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/IMG_6634-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/IMG_6634-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tCORTADERIA\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/cortaderia-en\/\">CORTADERIA<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/cortaderia\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13861 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-poppy-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09342-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09342-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09342-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09342-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09342-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tPOPPY O\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/poppy-en\/\">POPPY O<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Park Hallera Otwock<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/poppy-o-2\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13863 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-aster-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09340-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09340-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09340-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09340-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09340-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tASTER\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/aster-en\/\">ASTER<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Park Hallera Otwock<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/aster-4\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10941 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-hoya-l-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09329-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09329-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09329-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09329-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09329-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHOYA L\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/hoya-l-en\/\">HOYA L<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Hallera Park Otwock<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/hoya-l-5\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10943 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-calluna-sq-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09334-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09334-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09334-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09334-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09334-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tCALLUNA SQ\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/calluna-sq-en\/\">CALLUNA SQ<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Hallera Park Otwock<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/calluna-sq-2\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10947 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-n-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09345-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09345-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09345-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09345-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09345-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID N\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-n-en\/\">ORCHID N<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Hallera Otwock<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-n-9\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10945 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-nemesia-in-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09349-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09349-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09349-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09349-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09349-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tNEMESIA IN\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/nemesia-in-en\/\">NEMESIA IN<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Bagatela Park Otwock<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/nemesia-in-3\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10949 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-hoya-l\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09348-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09348-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09348-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09348-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09348-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHOYA L\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/portfolio-category\/hoya-l\/\">HOYA L<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Bagatela Otwock<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/hoya-l-4\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10951 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-primrose-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09357-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09357-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09357-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09357-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09357-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tPRIMROSE\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/primrose-en\/\">PRIMROSE<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Bagatela Otwock<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/primrose-2\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13865 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-n-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09372-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09372-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09372-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09372-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09372-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID N\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-n-en\/\">ORCHID N<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Park Bagatela Otwock<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-n-8\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10953 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-clove-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09364-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09364-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09364-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09364-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09364-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tCLOVE\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/clove-en\/\">CLOVE<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Park Bagatela Otwock<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/clove-2\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13867 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-aster-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09368-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09368-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09368-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09368-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/03\/DSC09368-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tASTER\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/aster-en\/\">ASTER<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Park Bagatela Otwock<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/aster-3\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10378 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-honey-honeycomb\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/02\/PHOTO-2024-02-14-12-24-00-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/02\/PHOTO-2024-02-14-12-24-00-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/02\/PHOTO-2024-02-14-12-24-00-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/02\/PHOTO-2024-02-14-12-24-00-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/02\/PHOTO-2024-02-14-12-24-00-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2024\/02\/PHOTO-2024-02-14-12-24-00-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHONEY HONEYCOMB\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/honey-honeycomb\/\">HONEY HONEYCOMB<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/honey-honeycomb-2\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10380 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-hoya-l-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/12\/DSC09134-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/12\/DSC09134-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/12\/DSC09134-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/12\/DSC09134-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/12\/DSC09134-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHOYA L\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/hoya-l-en\/\">HOYA L<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">HOYA L<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/hoya-l-3\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10382 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-nemesia-od-k-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/11\/beelight-Image-2023-11-14-at-11.04.10-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/11\/beelight-Image-2023-11-14-at-11.04.10-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/11\/beelight-Image-2023-11-14-at-11.04.10-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/11\/beelight-Image-2023-11-14-at-11.04.10-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/11\/beelight-Image-2023-11-14-at-11.04.10-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/11\/beelight-Image-2023-11-14-at-11.04.10-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tNEMESIA OD\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/nemesia-od-k-en\/\">NEMESIA OD K<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">NEMESIA OD<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/nemesia-od\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10384 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-sq-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/11\/beelight-Image-2023-11-14-at-11.04.17-1-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/11\/beelight-Image-2023-11-14-at-11.04.17-1-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/11\/beelight-Image-2023-11-14-at-11.04.17-1-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/11\/beelight-Image-2023-11-14-at-11.04.17-1-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/11\/beelight-Image-2023-11-14-at-11.04.17-1-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/11\/beelight-Image-2023-11-14-at-11.04.17-1-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID SQ\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-sq-en\/\">ORCHID SQ<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">ORCHID SQ<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-sq-2\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10386 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-p-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/11\/beelight-Image-2023-11-14-at-11.04.16-2-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/11\/beelight-Image-2023-11-14-at-11.04.16-2-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/11\/beelight-Image-2023-11-14-at-11.04.16-2-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/11\/beelight-Image-2023-11-14-at-11.04.16-2-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/11\/beelight-Image-2023-11-14-at-11.04.16-2-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/11\/beelight-Image-2023-11-14-at-11.04.16-2-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID P\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-p-en\/\">ORCHID P<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">ORCHID P<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-p-3\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10388 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-lily-o-n-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/11\/beelight-Image-2023-11-14-at-11.04.18-2-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/11\/beelight-Image-2023-11-14-at-11.04.18-2-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/11\/beelight-Image-2023-11-14-at-11.04.18-2-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/11\/beelight-Image-2023-11-14-at-11.04.18-2-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/11\/beelight-Image-2023-11-14-at-11.04.18-2-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/11\/beelight-Image-2023-11-14-at-11.04.18-2-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tLILY O N\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/lily-o-n-en\/\">LILY O N<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">LILY O N<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/lily-o-n\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10390 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-n-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/11\/beelight-Image-2023-11-14-at-11.04.18-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/11\/beelight-Image-2023-11-14-at-11.04.18-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/11\/beelight-Image-2023-11-14-at-11.04.18-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/11\/beelight-Image-2023-11-14-at-11.04.18-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/11\/beelight-Image-2023-11-14-at-11.04.18-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/11\/beelight-Image-2023-11-14-at-11.04.18-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID N\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-n-en\/\">ORCHID N<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">ORCHID N<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-n-7\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10392 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-od-n-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/11\/beelight-Image-2023-11-14-at-11.04.11-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/11\/beelight-Image-2023-11-14-at-11.04.11-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/11\/beelight-Image-2023-11-14-at-11.04.11-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/11\/beelight-Image-2023-11-14-at-11.04.11-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/11\/beelight-Image-2023-11-14-at-11.04.11-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/11\/beelight-Image-2023-11-14-at-11.04.11-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID OD N\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-od-n-en\/\">ORCHID OD N<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">ORCHID OD N<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-od-n-2\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10394 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-freesia-o-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/11\/beelight-Image-2023-11-14-at-11.04.20-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/11\/beelight-Image-2023-11-14-at-11.04.20-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/11\/beelight-Image-2023-11-14-at-11.04.20-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/11\/beelight-Image-2023-11-14-at-11.04.20-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/11\/beelight-Image-2023-11-14-at-11.04.20-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/11\/beelight-Image-2023-11-14-at-11.04.20-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tFREESIA O\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/freesia-o-en\/\">FREESIA O<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">FREESIA O<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/freesia-o-3\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10396 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09311-1-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09311-1-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09311-1-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09311-1-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09311-1-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tbrass and glass sphere\t<\/h6>\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Modern Space<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/mosiadz-i-kula-szklo\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10399 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-peony-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09306-1-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09306-1-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09306-1-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09306-1-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09306-1-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tPEONY\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/peony-en\/\">PEONY<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Modern Space<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/peony\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10401 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-nemesia-k-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09299-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09299-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09299-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09299-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09299-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tNEMESIA CK\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/nemesia-k-en\/\">NEMESIA K<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Modern Space<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/nemesia-ck\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10403 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-freesia-o-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09300-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09300-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09300-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09300-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09300-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tFREESIA O\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/freesia-o-en\/\">FREESIA O<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Modern Space<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/freesia-o-2\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10405 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-iris-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09281-1-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09281-1-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09281-1-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09281-1-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09281-1-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tIRIS\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/iris-en\/\">IRIS<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Modern Space<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/iris-4\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10407 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-calluna-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09275-1-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09275-1-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09275-1-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09275-1-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09275-1-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tCALLUNA O\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/calluna-en\/\">CALLUNA<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Modern Space<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/calluna-o\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10409 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-nemesia-in-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09280-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09280-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09280-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09280-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09280-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tNEMESIA IN\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/nemesia-in-en\/\">NEMESIA IN<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Modern Space<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/nemesia-in-2\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10411 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-lily-sq-n-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09294-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09294-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09294-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09294-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09294-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tLILY SQ N\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/lily-sq-n-en\/\">LILY SQ N<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Modern Space<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/lily-sq-n\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10413 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-lily-o-p-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09312-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09312-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09312-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09312-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09312-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tLILY O P\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/lily-o-p-en\/\">LILY O P<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Modern Space<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/lily-o-p-3\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10415 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-p-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09293-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09293-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09293-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09293-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09293-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID P\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-p-en\/\">ORCHID P<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Modern Space<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-p-2\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10417 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-freesia-o-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09158-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09158-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09158-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09158-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09158-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tFREESIA O\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/freesia-o-en\/\">FREESIA O<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">&#8220;M\u00f3j Ursus&amp;#8<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/freesia-o\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10420 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-aster-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09228-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09228-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09228-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09228-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09228-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tASTER\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/aster-en\/\">ASTER<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">&#8220;M\u00f3j Ursus&amp;#8<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/aster-2\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10422 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-clove-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09222-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09222-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09222-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09222-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09222-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tCLOVE\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/clove-en\/\">CLOVE<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">&#8220;M\u00f3j Ursus&amp;#8<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/clove\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10424 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-linia-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09201-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09201-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09201-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09201-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09201-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID N LINE\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-linia-en\/\">ORCHID LINIA<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">&#8220;M\u00f3j Ursus&amp;#8<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-n-linia\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10426 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-n-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09227-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09227-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09227-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09227-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09227-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID N\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-n-en\/\">ORCHID N<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">&#8220;M\u00f3j Ursus&amp;#8<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-n-6\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10428 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-hoya-l-mini-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09211-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09211-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09211-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09211-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09211-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHOYA L MINI and HOYA L MINI 30ST\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/hoya-l-mini-en\/\">HOYA L Mini<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">&#8220;M\u00f3j Ursus&amp;#8<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/hoya-l-mini-30st\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10430 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-lily-o-p-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09190-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09190-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09190-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09190-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09190-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tLILY O P\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/lily-o-p-en\/\">LILY O P<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">&#8220;M\u00f3j Ursus&amp;#8<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/lily-o-p-2\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10432 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-gk-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09189-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09189-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09189-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09189-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09189-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID GK\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-gk-en\/\">ORCHID GK<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">&#8220;M\u00f3j Ursus&amp;#8<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-gk-3\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10434 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-freesia-sq-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09199-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09199-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09199-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09199-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09199-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tFREESIA SQ\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/freesia-sq-en\/\">FREESIA SQ<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">&#8220;M\u00f3j Ursus&amp;#8<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/freesia-sq\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10436 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-freesia-sq-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09165-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09165-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09165-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09165-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09165-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tFREESIA SQ OD\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/freesia-sq-en\/\">FREESIA SQ<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">&#8220;M\u00f3j Ursus&amp;#8<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/freesia-sq-od\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10438 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-hoya-t-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09167-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09167-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09167-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09167-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09167-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHoya T\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/hoya-t-en\/\">HOYA T<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">&#8220;M\u00f3j Ursus&amp;#8<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/hoya-t\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10440 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-hoya-l-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09168-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09168-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09168-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09168-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/DSC09168-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHoya L\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/hoya-l-en\/\">HOYA L<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">&#8220;M\u00f3j Ursus&amp;#8<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/hoya-l-2\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10442 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-honey-r-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/PHOTO-2023-09-15-21-33-58-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/PHOTO-2023-09-15-21-33-58-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/PHOTO-2023-09-15-21-33-58-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/PHOTO-2023-09-15-21-33-58-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/PHOTO-2023-09-15-21-33-58-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/10\/PHOTO-2023-09-15-21-33-58-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHONEY R\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/honey-r-en\/\">HONEY R<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Honey R<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/honey-r-4\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10444 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-peony-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/DSC09186-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/DSC09186-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/DSC09186-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/DSC09186-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/DSC09186-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tPEONY Z\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/peony-en\/\">PEONY<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">&#8220;M\u00f3j Ursus&amp;#8<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/peony-z-2\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10446 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-peony-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/DSC09219-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/DSC09219-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/DSC09219-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/DSC09219-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/DSC09219-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tPEONY Z\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/peony-en\/\">PEONY<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">&#8220;M\u00f3j Ursus&amp;#8<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/peony-z\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10448 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-honey-r-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/DSC09158-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/DSC09158-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/DSC09158-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/DSC09158-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/DSC09158-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHONEY R\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/honey-r-en\/\">HONEY R<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">&#8220;M\u00f3j Ursus&amp;#8<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/honey-r-3\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10450 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-od-n-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/DSC09232-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/DSC09232-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/DSC09232-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/DSC09232-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/DSC09232-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID OD N\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-od-n-en\/\">ORCHID OD N<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">&#8220;\u017byczliwa Pra<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-od-n\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10452 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-hoya-l-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/DSC09266-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/DSC09266-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/DSC09266-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/DSC09266-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/DSC09266-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHOYA L\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/hoya-l-en\/\">HOYA L<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">&#8220;\u017byczliwa Pra<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/hoya-l\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10454 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-hoya-l-mini-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/DSC09261-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/DSC09261-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/DSC09261-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/DSC09261-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/DSC09261-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHOYA L MINI\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/hoya-l-mini-en\/\">HOYA L Mini<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">&#8220;\u017byczliwa Pra<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/hoya-l-mini-2\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10456 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-n-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/DSC09241-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/DSC09241-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/DSC09241-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/DSC09241-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/DSC09241-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID N\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-n-en\/\">ORCHID N<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">&#8220;\u017byczliwa Pra<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-n-5\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10458 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-honey-r-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/DSC09237-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/DSC09237-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/DSC09237-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/DSC09237-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/DSC09237-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHONEY R\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/honey-r-en\/\">HONEY R<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">&#8220;\u017byczliwa Pra<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/honey-r-2\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10460 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-ivy-os-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/IMG_20230715_122330_585-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/IMG_20230715_122330_585-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/IMG_20230715_122330_585-scaled-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/IMG_20230715_122330_585-scaled-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/IMG_20230715_122330_585-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/09\/IMG_20230715_122330_585-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tIVY OS\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/ivy-os-en\/\">IVY OS<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">IVY OS<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/ivy-os-rogalinek-hala-sportowa\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10462 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-aster-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/05\/DSC08623-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/05\/DSC08623-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/05\/DSC08623-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/05\/DSC08623-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/05\/DSC08623-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tASTER\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/aster-en\/\">ASTER<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/aster\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10464 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-iris-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/05\/DSC08627-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/05\/DSC08627-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/05\/DSC08627-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/05\/DSC08627-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/05\/DSC08627-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tIRIS\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/iris-en\/\">IRIS<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/iris-3\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10466 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-freesia-honeycomb-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/05\/IMG_6978-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/05\/IMG_6978-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/05\/IMG_6978-scaled-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/05\/IMG_6978-scaled-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/05\/IMG_6978-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/05\/IMG_6978-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tFREESIA HONEYCOMB GK\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/freesia-honeycomb-en\/\">FREESIA HONEYCOMB<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/freesia-honeycomb-gk\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10468 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-freesia-sq-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/05\/IMG_7004-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/05\/IMG_7004-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/05\/IMG_7004-scaled-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/05\/IMG_7004-scaled-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/05\/IMG_7004-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/05\/IMG_7004-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tFREESIA SQ GK\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/freesia-sq-en\/\">FREESIA SQ<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/freesia-sq-gk\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10470 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-freesia-o-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/05\/IMG_6983-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/05\/IMG_6983-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/05\/IMG_6983-scaled-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/05\/IMG_6983-scaled-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/05\/IMG_6983-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/05\/IMG_6983-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tFREESIA O GK\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/freesia-o-en\/\">FREESIA O<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/freesia-o-gk\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10472 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-hoya-lz-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/05\/IMG_7250-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/05\/IMG_7250-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/05\/IMG_7250-scaled-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/05\/IMG_7250-scaled-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/05\/IMG_7250-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/05\/IMG_7250-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHOYA LZ\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/hoya-lz-en\/\">HOYA LZ<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/hoya-lz\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10474 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-daisy-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/IMG_0828-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/IMG_0828-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/IMG_0828-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/IMG_0828-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/IMG_0828-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/IMG_0828-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tDAISY\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/daisy-en\/\">DAISY<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/daisy-3\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10476 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-p-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/IMG_0824-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/IMG_0824-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/IMG_0824-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/IMG_0824-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/IMG_0824-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/IMG_0824-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID P\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-p-en\/\">ORCHID P<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-p\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10478 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-honey-r-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/IMG_0822-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/IMG_0822-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/IMG_0822-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/IMG_0822-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/IMG_0822-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/IMG_0822-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHONEY R\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/honey-r-en\/\">HONEY R<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/honey-r\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10480 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-pz-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-03-at-11.14.09-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-03-at-11.14.09-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-03-at-11.14.09-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-03-at-11.14.09-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-03-at-11.14.09-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-03-at-11.14.09-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID PZ\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-pz-en\/\">ORCHID PZ<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-pz-3\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10482 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-lily-o-p-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-03-at-11.14.36-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-03-at-11.14.36-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-03-at-11.14.36-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-03-at-11.14.36-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-03-at-11.14.36-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-03-at-11.14.36-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tLILY O P\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/lily-o-p-en\/\">LILY O P<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/lily-o-p\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10484 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-gk-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-03-31-at-13.28.38-1-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-03-31-at-13.28.38-1-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-03-31-at-13.28.38-1-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-03-31-at-13.28.38-1-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-03-31-at-13.28.38-1-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-03-31-at-13.28.38-1-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID GK\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-gk-en\/\">ORCHID GK<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-gk-2\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10486 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-n-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-03-31-at-13.28.36-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-03-31-at-13.28.36-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-03-31-at-13.28.36-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-03-31-at-13.28.36-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-03-31-at-13.28.36-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-03-31-at-13.28.36-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID N\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-n-en\/\">ORCHID N<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-n-4\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10488 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-mallow-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-03-31-at-13.28.40-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-03-31-at-13.28.40-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-03-31-at-13.28.40-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-03-31-at-13.28.40-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-03-31-at-13.28.40-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-03-31-at-13.28.40-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tMALLOW\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/mallow-en\/\">MALLOW<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/mallow-2\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10490 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-lily-o-p-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-02-15-at-17.53.14-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-02-15-at-17.53.14-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-02-15-at-17.53.14-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-02-15-at-17.53.14-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-02-15-at-17.53.14-150x150.jpeg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tLILY O P\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/lily-o-p-en\/\">LILY O P<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/oswietlenie-zewnetrzne-centrum-handlowego\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10492 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-pz-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-07-at-10.35.51-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-07-at-10.35.51-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-07-at-10.35.51-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-07-at-10.35.51-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-07-at-10.35.51-150x150.jpeg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID PZ\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-pz-en\/\">ORCHID PZ<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-pz-2\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10494 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-iris-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-25-08-03-00-2-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-25-08-03-00-2-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-25-08-03-00-2-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-25-08-03-00-2-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-25-08-03-00-2-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-25-08-03-00-2-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tIRIS\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/iris-en\/\">IRIS<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">IRIS<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/iris-2\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10496 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-primrose-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-25-08-03-02-1-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-25-08-03-02-1-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-25-08-03-02-1-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-25-08-03-02-1-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-25-08-03-02-1-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-25-08-03-02-1-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tPRIMROSE\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/primrose-en\/\">PRIMROSE<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/primrose\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-10498 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-poppy-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-25-08-06-59-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-25-08-06-59-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-25-08-06-59-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-25-08-06-59-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-25-08-06-59-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-25-08-06-59-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tPOPPY O\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/poppy-en\/\">POPPY O<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">POPPY O&nbsp;<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/poppy-o\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13869 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-tagetes-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-25-08-07-00-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-25-08-07-00-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-25-08-07-00-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-25-08-07-00-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-25-08-07-00-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-25-08-07-00-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tTAGETES\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/tagetes-en\/\">TAGETES<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">TAGETES<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/tagetes\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13871 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-od-n-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-25-08-02-58-1-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-25-08-02-58-1-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-25-08-02-58-1-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-25-08-02-58-1-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-25-08-02-58-1-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-25-08-02-58-1-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID N OD &#8211; Mi\u0144sk Mazowiecki\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-od-n-en\/\">ORCHID OD N<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">ORCHID OD N<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-n-od-minsk-mazowiecki\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13873 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-n-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-25-08-03-00-1-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-25-08-03-00-1-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-25-08-03-00-1-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-25-08-03-00-1-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-25-08-03-00-1-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-25-08-03-00-1-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID N &#8211; Mi\u0144sk Mazowiecki\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-n-en\/\">ORCHID N<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">ORCHID N<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-n-minsk-mazowiecki\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13875 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-ivy-os-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-26-13-44-32-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-26-13-44-32-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-26-13-44-32-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-26-13-44-32-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-26-13-44-32-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2023\/02\/PHOTO-2023-01-26-13-44-32-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tIVY OS &#8211; Korty MOSiR Toru\u0144\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/ivy-os-en\/\">IVY OS<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">IVY OS<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/ivy-os-korty-mosir-torun\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13877 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-p-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/IMG_20221125_214626-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/IMG_20221125_214626-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/IMG_20221125_214626-scaled-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/IMG_20221125_214626-scaled-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/IMG_20221125_214626-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/IMG_20221125_214626-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID P SALVE \u0141\u00f3d\u017a\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-p-en\/\">ORCHID P<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-p-salve-lodz\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13879 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-honey-r-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/IMG_20221125_214514-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/IMG_20221125_214514-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/IMG_20221125_214514-scaled-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/IMG_20221125_214514-scaled-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/IMG_20221125_214514-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/IMG_20221125_214514-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHONEY R SALVE \u0141\u00f3d\u017a\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/honey-r-en\/\">HONEY R<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/honey-r-salve-lodz\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13881 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-clove-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/IMG_20221125_214453-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/IMG_20221125_214453-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/IMG_20221125_214453-scaled-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/IMG_20221125_214453-scaled-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/IMG_20221125_214453-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/IMG_20221125_214453-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tCLOVE SALVE \u0141\u00f3d\u017a\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/clove-en\/\">CLOVE<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/clove-salve-lodz-2\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13883 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-iris-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/iris-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/iris-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/iris-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/iris-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/iris-150x150.jpeg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tIRIS Parking Centrum Handlowego\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/iris-en\/\">IRIS<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/iris-parking-centrum-handlowego\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13885 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-pz-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/orchid-moya-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/orchid-moya-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/orchid-moya-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/orchid-moya-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/orchid-moya-150x150.jpeg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID PZ STACJA MOYA\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-pz-en\/\">ORCHID PZ<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-pz-stacja-moya\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13887 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-n-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/orchid-n-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/orchid-n-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/orchid-n-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/orchid-n-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/orchid-n-150x150.jpeg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID N\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-n-en\/\">ORCHID N<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-n-3\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13889 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-pz-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/orchid-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/orchid-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/orchid-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/orchid-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/orchid-150x150.jpeg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID PZ\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-pz-en\/\">ORCHID PZ<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-pz\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-13891 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-pz-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/orchid-pz1-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/orchid-pz1-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/orchid-pz1-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/orchid-pz1-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2022\/12\/orchid-pz1-150x150.jpeg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID PZ Sala Konferencyjna\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-pz-en\/\">ORCHID PZ<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\"><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-pz-sala-konferencyjna\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-3787 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"367\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2021\/07\/BeeLight_VG_017-scaled.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2021\/07\/BeeLight_VG_017-scaled.jpg 2560w, https:\/\/bee-light.pl\/wp-content\/uploads\/2021\/07\/BeeLight_VG_017-600x401.jpg 600w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tVivid Games &#8211; Bydgoszcz Office\t<\/h6>\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Office of the Games <\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/vivid-games-biuro-bydgoszcz\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-2947 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-daisy-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-10-at-13.40.37-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-10-at-13.40.37-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-10-at-13.40.37-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-10-at-13.40.37-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-10-at-13.40.37-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-10-at-13.40.37-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tDAISY\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/daisy-en\/\">DAISY<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">DAISY RECESSED INTO <\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/daisy-zaklad-opiekunczo-leczniczy-warszawa\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-2936 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-lily-o-p-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-10-at-13.38.12-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-10-at-13.38.12-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-10-at-13.38.12-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-10-at-13.38.12-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-10-at-13.38.12-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-10-at-13.38.12-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tLILY O P\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/lily-o-p-en\/\">LILY O P<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">LILY O P RECESSED IN<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/lily-o-p-basen-zaklad-opiekunczo-leczniczy-warszawa\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-2938 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-p-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-10-at-13.36.32-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-10-at-13.36.32-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-10-at-13.36.32-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-10-at-13.36.32-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-10-at-13.36.32-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-10-at-13.36.32-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID P\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-p-en\/\">ORCHID P<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">ORCHID P<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/windflower-zaklad-opiekunczo-leczniczy-warszawa\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-2911 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-rose-2\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-10-at-13.34.21-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-10-at-13.34.21-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-10-at-13.34.21-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-10-at-13.34.21-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-10-at-13.34.21-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-10-at-13.34.21-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tROSE N\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/rose-2\/\">ROSE<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">ROSE SURFACE<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/rose-n-zaklad-opiekunczo-leczniczy-warszawa\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-2900 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-gk-2\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2021\/03\/IMG_20210313_164037-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2021\/03\/IMG_20210313_164037-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2021\/03\/IMG_20210313_164037-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2021\/03\/IMG_20210313_164037-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2021\/03\/IMG_20210313_164037-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2021\/03\/IMG_20210313_164037-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tAESCULAP CHIFA &#8211; ORCHID LINE GK\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-gk-2\/\">ORCHID GK<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">ORCHID LINE GK ORCHI<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/aesculap-chifa-orchid-linia-gk\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-2743 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-n-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2021\/01\/Orchid-N-2021-01-15-at-09.42.55-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2021\/01\/Orchid-N-2021-01-15-at-09.42.55-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2021\/01\/Orchid-N-2021-01-15-at-09.42.55-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2021\/01\/Orchid-N-2021-01-15-at-09.42.55-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2021\/01\/Orchid-N-2021-01-15-at-09.42.55-150x150.jpeg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID N\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-n-en\/\">ORCHID N<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Solutions for buildi<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-n\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-2625 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/IMG_1639-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/IMG_1639-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/IMG_1639-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/IMG_1639-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/IMG_1639-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/IMG_1639-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID GK LINIA\t<\/h6>\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Orchid Recessed line<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-gk-linia\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-2628 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-lily-o-p-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/IMG_1599-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/IMG_1599-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/IMG_1599-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/IMG_1599-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/IMG_1599-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/IMG_1599-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tLILY O P\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/lily-o-p-en\/\">LILY O P<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Recessed version of <\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/lily-p\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-2630 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-gk-2\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/IMG_1555-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/IMG_1555-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/IMG_1555-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/IMG_1555-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/IMG_1555-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/IMG_1555-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID GK\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-gk-2\/\">ORCHID GK<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Recessed version of <\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-gk\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-2632 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-gk-2\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/IMG_1534-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/IMG_1534-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/IMG_1534-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/IMG_1534-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/IMG_1534-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/IMG_1534-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tORCHID GK OD\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-gk-2\/\">ORCHID GK<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Recessed outdoor lum<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-gk-od\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-2682 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/IMG_1507-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/IMG_1507-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/IMG_1507-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/IMG_1507-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/IMG_1507-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/IMG_1507-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tASTER OPAL\t<\/h6>\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Industrial luminaire<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/aster-opal-2\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-2685 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-daisy-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/IMG_1518-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/IMG_1518-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/IMG_1518-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/IMG_1518-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/IMG_1518-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/IMG_1518-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tDAISY &#8211; Ceiling-mounted luminaire\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/daisy-en\/\">DAISY<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Solutions for buildi<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/daisy-oprawa-nastropowa\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-2688 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/naswietlacz-przemyslowy-1-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/naswietlacz-przemyslowy-1-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/naswietlacz-przemyslowy-1-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/naswietlacz-przemyslowy-1-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/naswietlacz-przemyslowy-1-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/naswietlacz-przemyslowy-1-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tSEVILLA\t<\/h6>\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Industrial outdoor l<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/naswietlacz-przemyslowy\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-2690 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/crocus-1-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/crocus-1-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/crocus-1-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/crocus-1-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/crocus-1-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/crocus-1-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tCROCUS\t<\/h6>\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Ceiling-mounted indu<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/crocus\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-2692 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/lucente-14-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/lucente-14-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/lucente-14-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/lucente-14-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/lucente-14-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/lucente-14-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tLucente\t<\/h6>\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Industrial lighting<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/lucente-fosnova\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-2694 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-iris-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/iris-5-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/iris-5-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/iris-5-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/iris-5-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/iris-5-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/iris-5-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tIRIS\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/iris-en\/\">IRIS<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Outdoor lighting<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/oprawy-iris\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-2696 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-daisy-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/daisy-8-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/daisy-8-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/daisy-8-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/daisy-8-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/daisy-8-150x150.jpeg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/daisy-8-1100x1100.jpeg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tDAISY &#8211; modular ceiling\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/daisy-en\/\">DAISY<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Recessed luminaires <\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/oprawa-daisy-sufit-modulowy\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-2699 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/sevilla-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/sevilla-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/sevilla-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/sevilla-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/sevilla-150x150.jpeg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tSEVILLA\t<\/h6>\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Industrial luminaire<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/naswietlacz-sevilla\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-2701 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/tulip-cortina-3-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/tulip-cortina-3-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/tulip-cortina-3-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/tulip-cortina-3-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/12\/tulip-cortina-3-150x150.jpeg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tTULIP &#8211; Tile showroom\t<\/h6>\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Cortina Tile Showroo<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/oprawy-tulip-salon-plytek\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-2704 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/20201113_120713000_iOS-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/20201113_120713000_iOS-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/20201113_120713000_iOS-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/20201113_120713000_iOS-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/20201113_120713000_iOS-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/20201113_120713000_iOS-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tASTER\t<\/h6>\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Garage lighting | Fo<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/aster-opal\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-2707 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/20201113_120707000_iOS-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/20201113_120707000_iOS-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/20201113_120707000_iOS-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/20201113_120707000_iOS-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/20201113_120707000_iOS-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/20201113_120707000_iOS-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHONEY L Slim\t<\/h6>\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Suspended luminaires<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/honey-l-slim-2\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-2709 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"347\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/Honey-Honeycomb-347x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHONEY Honeycomb\t<\/h6>\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Architectural lumina<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/honey-honeycomb\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-2711 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/lucente-2-550x550.jpeg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/lucente-2-550x550.jpeg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/lucente-2-300x300.jpeg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/lucente-2-100x100.jpeg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/lucente-2-150x150.jpeg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tLucente\t<\/h6>\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Industrial Luminaire<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/lucente\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-2713 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/20201113_120730000_iOS-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/20201113_120730000_iOS-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/20201113_120730000_iOS-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/20201113_120730000_iOS-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/20201113_120730000_iOS-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/20201113_120730000_iOS-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHONEY L Slim\t<\/h6>\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">For building develop<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/honey-l-slim\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-2715 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/20201113_093417000_iOS-1-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/20201113_093417000_iOS-1-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/20201113_093417000_iOS-1-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/20201113_093417000_iOS-1-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/20201113_093417000_iOS-1-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/20201113_093417000_iOS-1-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tLILY SQ P\t<\/h6>\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">For building develop<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/lily-sq-p\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-2717 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/20201113_084639000_iOS-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/20201113_084639000_iOS-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/20201113_084639000_iOS-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/20201113_084639000_iOS-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/20201113_084639000_iOS-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/20201113_084639000_iOS-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tCALLUNA SQ E27 | NEMESIA IN\t<\/h6>\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">For building develop<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/calluna-sq-e27-nemesia-in\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-2719 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/20201113_225834000_iOS-1-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/20201113_225834000_iOS-1-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/20201113_225834000_iOS-1-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/20201113_225834000_iOS-1-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/20201113_225834000_iOS-1-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/20201113_225834000_iOS-1-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tFERN | HOYA L\t<\/h6>\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">For building develop<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/fern-hoya-l\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-2721 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/20201113_140418000_iOS-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/20201113_140418000_iOS-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/20201113_140418000_iOS-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/20201113_140418000_iOS-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/20201113_140418000_iOS-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/11\/20201113_140418000_iOS-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tNEMESIA\t<\/h6>\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">For Building Develop<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/nemesia\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-1866 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-gk-2\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/117524423_2118023564988763_3023950349770002151_o-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/117524423_2118023564988763_3023950349770002151_o-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/117524423_2118023564988763_3023950349770002151_o-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/117524423_2118023564988763_3023950349770002151_o-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/117524423_2118023564988763_3023950349770002151_o-150x150.jpg 150w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tOrchid GK\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-gk-2\/\">ORCHID GK<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">normobaric chamber<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-gk-dali\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-1868 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_131922-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_131922-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_131922-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_131922-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_131922-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_131922-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tOrchid\t<\/h6>\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">architectural soluti<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/orchid-nastropowy\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-1977 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/3941229A-D3DE-43DA-8463-58065ABA8C15-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/3941229A-D3DE-43DA-8463-58065ABA8C15-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/3941229A-D3DE-43DA-8463-58065ABA8C15-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/3941229A-D3DE-43DA-8463-58065ABA8C15-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/3941229A-D3DE-43DA-8463-58065ABA8C15-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/3941229A-D3DE-43DA-8463-58065ABA8C15-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tTulip\t<\/h6>\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">restaurant lighting<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/15\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-1981 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_121103-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_121103-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_121103-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_121103-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_121103-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_121103-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tIris\t<\/h6>\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">outdoor lighting<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/14\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-1983 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-gk-2 portfolio-category-orchid-n-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_123020-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_123020-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_123020-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_123020-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_123020-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_123020-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tOrchid N | Orchid GK\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-gk-2\/\">ORCHID GK<\/a>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-n-en\/\">ORCHID N<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">recessed and ceiling<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/13\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-1986 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_130744-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_130744-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_130744-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_130744-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_130744-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_130744-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tPrimrose\t<\/h6>\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">outdoor and wall lig<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/12\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-1988 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_122745-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_122745-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_122745-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_122745-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_122745-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_122745-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tOrchid E27\t<\/h6>\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">outdoor and ceiling-<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/11\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-1991 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_120510-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_120510-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_120510-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_120510-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_120510-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_120510-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tFreesia\t<\/h6>\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">outdoor and ceiling-<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/10\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-1993 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_122309-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_122309-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_122309-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_122309-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_122309-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_122309-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tPoppy\t<\/h6>\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">ceiling-mounted ligh<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/9\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-1995 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_113056-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_113056-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_113056-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_113056-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_113056-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_113056-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tAster\t<\/h6>\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">wall and ceiling-mou<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/1230\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-1997 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-od-n-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_113437-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_113437-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_113437-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_113437-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_113437-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_113437-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tOrchid Outdoor\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-od-n-en\/\">ORCHID OD N<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">outdoor lighting<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/7\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-1999 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-orchid-n-en\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_131629-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_131629-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_131629-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_131629-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_131629-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_131629-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tOrchid | Nemesia In\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/en\/portfolio-category\/orchid-n-en\/\">ORCHID N<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">architectural and ou<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/6\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-2001 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-clove\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/DSC05807-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/DSC05807-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/DSC05807-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/DSC05807-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/DSC05807-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/DSC05807-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tClove\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/portfolio-category\/clove\/\">CLOVE<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">ceiling and wall lig<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/5\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-2003 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-hoya-l-mini\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_130511-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_130511-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_130511-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_130511-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_130511-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/20200914_130511-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHoya\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/portfolio-category\/hoya-l-mini\/\">HOYA L Mini<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">outdoor lighting<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/4\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-2005 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/DSC05797-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/DSC05797-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/DSC05797-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/DSC05797-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/DSC05797-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/DSC05797-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHoya | Iris | Pansy | Phlox\t<\/h6>\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">sports outdoor light<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/3\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-2007 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/PHOTO-2020-09-10-10-47-39-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/PHOTO-2020-09-10-10-47-39-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/PHOTO-2020-09-10-10-47-39-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/PHOTO-2020-09-10-10-47-39-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/PHOTO-2020-09-10-10-47-39-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/PHOTO-2020-09-10-10-47-39-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tSnowdrop | Orchid | Freesia | Lily\t<\/h6>\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">school lighting<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/2\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\n<article class=\"edgtf-pl-item edgtf-pl-masonry-default post-2009 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-honey-r\"  >\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/9A20573A-0757-4318-9861-A810AB06F204-550x550.jpg\" class=\"attachment-maison_image_square size-maison_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/9A20573A-0757-4318-9861-A810AB06F204-550x550.jpg 550w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/9A20573A-0757-4318-9861-A810AB06F204-300x300.jpg 300w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/9A20573A-0757-4318-9861-A810AB06F204-100x100.jpg 100w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/9A20573A-0757-4318-9861-A810AB06F204-150x150.jpg 150w, https:\/\/bee-light.pl\/wp-content\/uploads\/2020\/09\/9A20573A-0757-4318-9861-A810AB06F204-1100x1100.jpg 1100w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t<\/div>\n<div class=\"edgtf-pli-text-holder\">\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h6 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tHoney R | Orchid | Dahlia\t<\/h6>\n\t\t\t\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/bee-light.pl\/portfolio-category\/honey-r\/\">HONEY R<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">for developers<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\n\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/bee-light.pl\/en\/portfolio-item\/1\/\" target=\"_self\"><\/a>\n\t\t\t<\/div>\n<\/article>\t<\/div>\n\t\n\t<\/div>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_empty_space][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full-width.php","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"acf":[],"_links":{"self":[{"href":"https:\/\/bee-light.pl\/en\/wp-json\/wp\/v2\/pages\/243"}],"collection":[{"href":"https:\/\/bee-light.pl\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bee-light.pl\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bee-light.pl\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bee-light.pl\/en\/wp-json\/wp\/v2\/comments?post=243"}],"version-history":[{"count":12,"href":"https:\/\/bee-light.pl\/en\/wp-json\/wp\/v2\/pages\/243\/revisions"}],"predecessor-version":[{"id":13589,"href":"https:\/\/bee-light.pl\/en\/wp-json\/wp\/v2\/pages\/243\/revisions\/13589"}],"wp:attachment":[{"href":"https:\/\/bee-light.pl\/en\/wp-json\/wp\/v2\/media?parent=243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}